{"id":175983,"date":"2025-02-24T19:35:31","date_gmt":"2025-02-24T18:35:31","guid":{"rendered":"https:\/\/trimakasi.eu\/?post_type=product&#038;p=175983"},"modified":"2026-08-14T10:55:43","modified_gmt":"2026-08-14T08:55:43","slug":"collana-pietra-di-luna-goccia-dellintuizione-3","status":"publish","type":"product","link":"https:\/\/trimakasi.eu\/it\/product\/choker-necklace-moonstone\/","title":{"rendered":"Collana girocollo con pietra di luna"},"content":{"rendered":"<h3>Pietra di luna \u2013 Significato<\/h3>\n<p>La delicata e argentea lucentezza della pietra di luna, nota come adularescenza, sembra aleggiare appena sotto la superficie, donando a ogni perla un sottile luccichio. Si dice che porti equilibrio alle emozioni a un livello profondo e subconscio, rafforzi l&#039;intuizione, aiuti ad ascoltare la propria voce interiore e allevi lo stress derivante da una vita lavorativa impegnativa.<\/p>\n<p>In India, la pietra di luna \u00e8 venerata da secoli come &quot;Chandra Kant Mani&quot;, una delle pietre pi\u00f9 sacre della tradizione induista. Simboleggia la speranza, la purezza spirituale e la liberazione dall&#039;ego, e si crede che aiuti chi la indossa a resistere al materialismo e a rafforzare la fede in ogni religione, non solo nell&#039;induismo. Secondo la mitologia induista, la pietra di luna stessa nacque dalla luce lunare, formandosi \u2013 narra la leggenda \u2013 dai raggi pietrificati della luna. Da tempo \u00e8 considerata un dono d&#039;amore per le donne, poich\u00e9 si crede che risvegli l&#039;amore e al contempo ripristini l&#039;equilibrio emotivo.<\/p>\n<p>Paese d&#039;origine: <strong>Sri Lanka<\/strong><\/p>\n<p>Elemento: <strong>Fuoco, Terra<\/strong><\/p>\n<p>Segno zodiacale: <strong>Capricorno, Leone, Scorpione, Acquario<\/strong><\/p>\n<p>Questa collana girocollo armonizza i chakra della gola e della corona.<\/p>\n<p><a href=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-138515\" src=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra5.jpg\" alt=\"Chakra della gola\" width=\"81\" height=\"87\" srcset=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra5.jpg 81w, https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra5-11x12.jpg 11w\" sizes=\"auto, (max-width: 81px) 100vw, 81px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-138516\" src=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra6.jpg\" alt=\"Chakra del terzo occhio\" width=\"103\" height=\"98\" srcset=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra6.jpg 103w, https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra6-13x12.jpg 13w\" sizes=\"auto, (max-width: 103px) 100vw, 103px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-132743\" src=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/crown-chakra.jpg\" alt=\"Chakra della corona\" width=\"92\" height=\"102\" srcset=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/crown-chakra.jpg 92w, https:\/\/trimakasi.eu\/wp-content\/uploads\/crown-chakra-11x12.jpg 11w\" sizes=\"auto, (max-width: 92px) 100vw, 92px\" \/><\/a><a href=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/crown-chakra.jpg\"><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Un elegante girocollo realizzato in pietra di luna naturale. Piccole perle rondelle sfaccettate aderiscono al collo e catturano la luce con delicati riflessi blu, un aspetto caratteristico della pietra di luna. Il design minimalista rende questa collana facile da indossare tutti i giorni e perfetta per chi ama i gioielli essenziali e senza tempo.<\/p>\n<p>\u00c8 anche molto facile da abbinare: indossala da sola per un look semplice e raffinato, oppure sovrapponila a collane pi\u00f9 lunghe per creare un look moderno e di tendenza.<\/p>\n<p>La collana ha una chiusura regolabile, quindi si adatta comodamente a diverse circonferenze del collo e rimane comoda da indossare tutto il giorno.<\/p>","protected":false},"featured_media":175350,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_themeisle_gutenberg_block_has_review":false},"product_brand":[],"product_cat":[569,1690,1149,1316,553],"product_tag":[],"class_list":["post-175983","product","type-product","status-publish","has-post-thumbnail","product_cat-minimalist-jewellery-for-women","product_cat-necklaces","product_cat-necklaces-for-women","product_cat-rare-gemstone-bracelets","product_cat-womens-jewellery","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"_links":{"self":[{"href":"https:\/\/trimakasi.eu\/it\/wp-json\/wp\/v2\/product\/175983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trimakasi.eu\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/trimakasi.eu\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/trimakasi.eu\/it\/wp-json\/wp\/v2\/comments?post=175983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trimakasi.eu\/it\/wp-json\/wp\/v2\/media\/175350"}],"wp:attachment":[{"href":"https:\/\/trimakasi.eu\/it\/wp-json\/wp\/v2\/media?parent=175983"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/trimakasi.eu\/it\/wp-json\/wp\/v2\/product_brand?post=175983"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/trimakasi.eu\/it\/wp-json\/wp\/v2\/product_cat?post=175983"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/trimakasi.eu\/it\/wp-json\/wp\/v2\/product_tag?post=175983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}