{"id":175958,"date":"2020-01-01T01:00:00","date_gmt":"2020-01-01T00:00:00","guid":{"rendered":"https:\/\/trimakasi.eu\/?post_type=product&#038;p=175958"},"modified":"2026-08-11T17:44:10","modified_gmt":"2026-08-11T15:44:10","slug":"tourmaline-3","status":"publish","type":"product","link":"https:\/\/trimakasi.eu\/fr\/product\/flower-bracelet-pink-tourmaline-moonstone-fleur-eterna\/","title":{"rendered":"Bracelet Fleur Eterna en tourmaline rose et pierre de lune"},"content":{"rendered":"<h3>Collection Fleur Eterna \u2013 La Fleur \u00c9ternelle<\/h3>\n<p>De la pierre est n\u00e9e une fleur. La duret\u00e9 s&#039;est mu\u00e9e en douceur. La force de la nature s&#039;est unie \u00e0 la beaut\u00e9 de l&#039;\u00e2me. La collection Fleur Eterna porte en elle l&#039;\u00e9nergie des pierres pr\u00e9cieuses et le symbolisme de la fleur \u2013 une union de force et de tendresse, une essence m\u00eame de chaque femme. Elle rend hommage \u00e0 la f\u00e9minit\u00e9 : d\u00e9licate, sensible et pourtant in\u00e9branlable. Chaque regard pos\u00e9 sur ce bijou vous rappelle qu&#039;en vous coexistent calme et passion, force et douceur \u2013 et que votre puissance int\u00e9rieure s&#039;\u00e9panouit lorsque vous vous reconnectez \u00e0 vous-m\u00eame.<\/p>\n<h3>Pierre de lune \u2013 Signification<\/h3>\n<p>L&#039;\u00e9clat doux et argent\u00e9 de la pierre de lune, appel\u00e9 adularescence, semble flotter juste sous sa surface, conf\u00e9rant \u00e0 chaque perle un subtil scintillement. On dit qu&#039;elle apporte l&#039;\u00e9quilibre \u00e9motionnel \u00e0 un niveau profond et inconscient, et qu&#039;elle apaise le stress li\u00e9 \u00e0 une vie professionnelle exigeante.<\/p>\n<p>En Inde, la pierre de lune est v\u00e9n\u00e9r\u00e9e depuis des si\u00e8cles sous le nom de \u201c Chandra Kant Mani \u201d, l&#039;une des pierres les plus sacr\u00e9es de la tradition hindoue. Elle symbolise l&#039;espoir, la puret\u00e9 spirituelle et le d\u00e9tachement de l&#039;ego, et on lui pr\u00eate le pouvoir d&#039;aider celui ou celle qui la porte \u00e0 r\u00e9sister au mat\u00e9rialisme et \u00e0 renforcer la foi, et ce, dans toutes les religions, et pas seulement dans l&#039;hindouisme. Selon la mythologie hindoue, la pierre de lune serait n\u00e9e du clair de lune, form\u00e9e, dit la l\u00e9gende, par les rayons p\u00e9trifi\u00e9s de la lune. Elle est depuis longtemps consid\u00e9r\u00e9e comme un pr\u00e9sent d&#039;amour pour les femmes, car on lui attribue le pouvoir d&#039;\u00e9veiller l&#039;amour tout en restaurant discr\u00e8tement l&#039;\u00e9quilibre \u00e9motionnel.<\/p>\n<p>Pays d&#039;origine: <strong>Sri Lanka<\/strong><\/p>\n<p>\u00c9l\u00e9ment: <strong>L&#039;eau<\/strong><\/p>\n<p>Signe du zodiaque: <strong>Cancer, G\u00e9meaux, Poissons, Scorpion<\/strong><\/p>\n<h3>Tourmaline rose<\/h3>\n<p>La tourmaline rose, aussi appel\u00e9e rubellite, est souvent per\u00e7ue comme une pierre profond\u00e9ment r\u00e9confortante, associ\u00e9e \u00e0 la lib\u00e9ration du poids \u00e9motionnel accumul\u00e9 au fil du temps. Elle est li\u00e9e au l\u00e2cher-prise des sentiments ind\u00e9sirables, des vieilles blessures \u00e9motionnelles et des sch\u00e9mas qui nous retiennent prisonniers du pass\u00e9. Nombreux sont ceux qui associent la rubellite \u00e0 l&#039;apaisement des \u00e9tats int\u00e9rieurs pesants tels que la culpabilit\u00e9, la tristesse ou l&#039;anxi\u00e9t\u00e9, et \u00e0 une douce orientation de cette \u00e9nergie vers l&#039;acceptation et l&#039;amour de soi. Non pas comme une solution miracle, mais plut\u00f4t comme un petit rappel quotidien pour se d\u00e9tendre, respirer et se reconnecter \u00e0 soi-m\u00eame. Li\u00e9e au c\u0153ur, la rubellite est \u00e9galement choisie par ceux qui souhaitent s&#039;ouvrir \u00e9motionnellement, avec plus de bienveillance envers eux-m\u00eames et plus de courage pour ressentir leurs \u00e9motions sans se replier sur eux-m\u00eames.<\/p>\n<p>\u00c9l\u00e9ment: <strong>Eau, Terre<\/strong><\/p>\n<p>Signe du zodiaque: <strong>Capricorne, G\u00e9meaux, Scorpion, Balance<\/strong><\/p>\n<p>Ce bracelet harmonise les chakras Racine, C\u0153ur, Troisi\u00e8me \u0152il et Couronne.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"88\" style=\"width:84px;height:84px;object-fit:contain;vertical-align:middle;margin:0 3px\" class=\"alignnone size-full wp-image-138513\" src=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra1.jpg\" alt=\"Chakra racine\" srcset=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra1.jpg 81w, https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra1-11x12.jpg 11w\" sizes=\"auto, (max-width: 81px) 100vw, 81px\" \/> <img loading=\"lazy\" decoding=\"async\" width=\"79\" height=\"93\" style=\"width:84px;height:84px;object-fit:contain;vertical-align:middle;margin:0 3px\" class=\"alignnone size-full wp-image-83566\" src=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/2020\/07\/\u010dakra4.jpg\" alt=\"Chakra du coeur\" srcset=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/2020\/07\/\u010dakra4.jpg 79w, https:\/\/trimakasi.eu\/wp-content\/uploads\/2020\/07\/\u010dakra4-10x12.jpg 10w\" sizes=\"auto, (max-width: 79px) 100vw, 79px\" \/> <img loading=\"lazy\" decoding=\"async\" width=\"81\" height=\"87\" style=\"width:84px;height:84px;object-fit:contain;vertical-align:middle;margin:0 3px\" class=\"alignnone size-full wp-image-138515\" src=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra5.jpg\" alt=\"Chakra de la gorge\" srcset=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra5.jpg 81w, https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra5-11x12.jpg 11w\" sizes=\"auto, (max-width: 81px) 100vw, 81px\" \/> <img loading=\"lazy\" decoding=\"async\" width=\"103\" height=\"98\" style=\"width:84px;height:84px;object-fit:contain;vertical-align:middle;margin:0 3px\" class=\"alignnone size-full wp-image-138516\" src=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra6.jpg\" alt=\"Chakra du troisi\u00e8me \u0153il\" srcset=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra6.jpg 103w, https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra6-13x12.jpg 13w\" sizes=\"auto, (max-width: 103px) 100vw, 103px\" \/> <img loading=\"lazy\" decoding=\"async\" width=\"92\" height=\"102\" style=\"width:84px;height:84px;object-fit:contain;vertical-align:middle;margin:0 3px\" class=\"alignnone size-full wp-image-132743\" src=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/crown-chakra.jpg\" alt=\"Chakra de la couronne\" srcset=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/crown-chakra.jpg 92w, https:\/\/trimakasi.eu\/wp-content\/uploads\/crown-chakra-11x12.jpg 11w\" sizes=\"auto, (max-width: 92px) 100vw, 92px\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Un bracelet pour femme en tourmaline rose et pierre de lune, inspir\u00e9 d&#039;un motif floral \u2014 symbole de croissance, de douceur et du courage de s&#039;\u00e9panouir.<\/p>\n<p>Des fleurs taill\u00e9es \u00e0 la main dans des pierres pr\u00e9cieuses facett\u00e9es sont enfil\u00e9es sur un cordon en nylon blanc ajustable. Des d\u00e9tails en acier inoxydable plaqu\u00e9s or 18 carats compl\u00e8tent l&#039;ensemble\u00a0: d\u00e9licat et expressif \u00e0 la fois.<\/p>\n<p>La tourmaline rose est souvent associ\u00e9e \u00e0 l&#039;ouverture du c\u0153ur \u00e0 l&#039;amour, tandis que la pierre de lune est li\u00e9e \u00e0 l&#039;intuition et \u00e0 l&#039;\u00e9coute de sa voix int\u00e9rieure.<\/p>\n<p>Pr\u00e9sent\u00e9 dans un \u00e9l\u00e9gant coffret cadeau blanc Trimakasi, car les beaux cadeaux m\u00e9ritent un bel emballage.<\/p>","protected":false},"featured_media":175633,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_themeisle_gutenberg_block_has_review":false},"product_brand":[],"product_cat":[1688,570,569,1689,553],"product_tag":[],"class_list":["post-175958","product","type-product","status-publish","has-post-thumbnail","product_cat-braided-bracelets","product_cat-braided-bracelets-for-women","product_cat-minimalist-jewellery-for-women","product_cat-simple-bracelets","product_cat-womens-jewellery","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"_links":{"self":[{"href":"https:\/\/trimakasi.eu\/fr\/wp-json\/wp\/v2\/product\/175958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trimakasi.eu\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/trimakasi.eu\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/trimakasi.eu\/fr\/wp-json\/wp\/v2\/comments?post=175958"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trimakasi.eu\/fr\/wp-json\/wp\/v2\/media\/175633"}],"wp:attachment":[{"href":"https:\/\/trimakasi.eu\/fr\/wp-json\/wp\/v2\/media?parent=175958"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/trimakasi.eu\/fr\/wp-json\/wp\/v2\/product_brand?post=175958"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/trimakasi.eu\/fr\/wp-json\/wp\/v2\/product_cat?post=175958"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/trimakasi.eu\/fr\/wp-json\/wp\/v2\/product_tag?post=175958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}