{"id":174503,"date":"2023-02-03T23:00:08","date_gmt":"2023-02-03T22:00:08","guid":{"rendered":"https:\/\/trimakasi.eu\/?post_type=product&#038;p=174503"},"modified":"2026-08-11T17:44:00","modified_gmt":"2026-08-11T15:44:00","slug":"bracelet-rondelle-jaspe-kambaba","status":"publish","type":"product","link":"https:\/\/trimakasi.eu\/fr\/product\/kambaba-jasper-rondelle-bracelet\/","title":{"rendered":"Bracelet Rondelle Jaspe Kambaba"},"content":{"rendered":"<h3>Jaspe Kambaba \u2013 Signification<\/h3>\n<p>Le jaspe kambaba est r\u00e9put\u00e9 pour sa riche histoire et ses motifs saisissants d&#039;un vert fonc\u00e9 et de noir. Les peuples anciens croyaient que cette pierre recelait la puissance combin\u00e9e de la terre et de l&#039;oc\u00e9an et l&#039;utilisaient comme talisman pour s&#039;ancrer et trouver le calme en p\u00e9riode de troubles. La l\u00e9gende raconte que porter du jaspe kambaba facilite la connexion \u00e0 la sagesse de la nature, favorise l&#039;harmonie int\u00e9rieure et prot\u00e8ge des influences n\u00e9gatives.<\/p>\n<p>\u00c9l\u00e9ment: <strong>Terre<\/strong><\/p>\n<p>Signe du zodiaque: <strong>Vierge, Taureau, Capricorne, Cancer<\/strong><\/p>\n<p>Ce bracelet harmonise les chakras Racine et C\u0153ur.<\/p>\n<p><a href=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-138513\" src=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra1.jpg\" alt=\"Chakra racine\" width=\"81\" height=\"88\" srcset=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra1.jpg 81w, https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra1-11x12.jpg 11w\" sizes=\"auto, (max-width: 81px) 100vw, 81px\" \/><\/a><a href=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/2020\/07\/\u010dakra4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-83566\" src=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/2020\/07\/\u010dakra4.jpg\" alt=\"Chakra du coeur\" width=\"79\" height=\"93\" srcset=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/2020\/07\/\u010dakra4.jpg 79w, https:\/\/trimakasi.eu\/wp-content\/uploads\/2020\/07\/\u010dakra4-10x12.jpg 10w\" sizes=\"auto, (max-width: 79px) 100vw, 79px\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Ce bracelet rondelle en jaspe Kambaba est fabriqu\u00e9 \u00e0 partir d&#039;une pierre rare dont les volutes vert fonc\u00e9 et noires se seraient form\u00e9es \u00e0 partir d&#039;algues fossilis\u00e9es, parmi les formes de vie les plus anciennes sur Terre.<\/p>\n<p>Parfois appel\u00e9e pierre des \u00e9nergies ancestrales, la jaspe kambaba est traditionnellement consid\u00e9r\u00e9e comme une pierre protectrice de calme et de stabilit\u00e9. Disponible en deux tailles ajustables pour femmes et hommes, avec des composants en acier inoxydable plaqu\u00e9 or 18 carats.<\/p>","protected":false},"featured_media":174475,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_themeisle_gutenberg_block_has_review":false},"product_brand":[],"product_cat":[1069,1064,569,1718,1689,553],"product_tag":[],"class_list":["post-174503","product","type-product","status-publish","has-post-thumbnail","product_cat-braided-bracelets-for-men","product_cat-mens-jewellery","product_cat-minimalist-jewellery-for-women","product_cat-minimalist-jewellery-for-men","product_cat-simple-bracelets","product_cat-womens-jewellery","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"_links":{"self":[{"href":"https:\/\/trimakasi.eu\/fr\/wp-json\/wp\/v2\/product\/174503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trimakasi.eu\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/trimakasi.eu\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/trimakasi.eu\/fr\/wp-json\/wp\/v2\/comments?post=174503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trimakasi.eu\/fr\/wp-json\/wp\/v2\/media\/174475"}],"wp:attachment":[{"href":"https:\/\/trimakasi.eu\/fr\/wp-json\/wp\/v2\/media?parent=174503"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/trimakasi.eu\/fr\/wp-json\/wp\/v2\/product_brand?post=174503"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/trimakasi.eu\/fr\/wp-json\/wp\/v2\/product_cat?post=174503"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/trimakasi.eu\/fr\/wp-json\/wp\/v2\/product_tag?post=174503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}