{"id":175983,"date":"2025-02-24T19:35:31","date_gmt":"2025-02-24T18:35:31","guid":{"rendered":"https:\/\/trimakasi.eu\/?post_type=product&#038;p=175983"},"modified":"2026-08-14T10:55:43","modified_gmt":"2026-08-14T08:55:43","slug":"mondstein-halskette-tropfen-der-intuition-3","status":"publish","type":"product","link":"https:\/\/trimakasi.eu\/de\/product\/choker-necklace-moonstone\/","title":{"rendered":"Choker-Halskette mit Mondstein"},"content":{"rendered":"<h3>Mondstein \u2013 Bedeutung<\/h3>\n<p>Der sanfte, silbrige Schimmer des Mondsteins \u2013 bekannt als Adulareszenz \u2013 scheint knapp unter der Oberfl\u00e4che des Steins zu schweben und verleiht jeder Perle ein subtiles Funkeln. Er soll auf einer tiefen, unbewussten Ebene f\u00fcr emotionale Ausgeglichenheit sorgen, die Intuition st\u00e4rken, das H\u00f6ren auf die innere Stimme erleichtern und den Stress eines anspruchsvollen Berufslebens lindern.<\/p>\n<p>In Indien wird der Mondstein seit Jahrhunderten als \u201cChandra Kant Mani\u201d verehrt \u2013 er z\u00e4hlt zu den heiligsten Steinen der hinduistischen Tradition. Er steht f\u00fcr Hoffnung, spirituelle Reinheit und die Befreiung vom Ego und soll seinem Tr\u00e4ger helfen, dem Materialismus zu widerstehen und den Glauben in allen Religionen, nicht nur im Hinduismus, zu st\u00e4rken. Der hinduistischen Mythologie zufolge entstand der Mondstein selbst aus Mondlicht, geformt \u2013 so die Legende \u2013 aus den versteinerten Strahlen des Mondes. Er gilt seit Langem als Liebesgeschenk f\u00fcr Frauen und soll die Liebe wecken und gleichzeitig das emotionale Gleichgewicht wiederherstellen.<\/p>\n<p>Herkunftsland: <strong>Sri Lanka<\/strong><\/p>\n<p>Element: <strong>Feuer, Erde<\/strong><\/p>\n<p>Tierkreiszeichen: <strong>Steinbock, L\u00f6we, Skorpion, Wassermann<\/strong><\/p>\n<p>Diese Choker-Halskette harmonisiert das Hals- und Kronenchakra.<\/p>\n<p><a href=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-138515\" src=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra5.jpg\" alt=\"Halschakra\" width=\"81\" height=\"87\" srcset=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra5.jpg 81w, https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra5-11x12.jpg 11w\" sizes=\"auto, (max-width: 81px) 100vw, 81px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-138516\" src=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra6.jpg\" alt=\"Chakra des dritten Auges\" width=\"103\" height=\"98\" srcset=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra6.jpg 103w, https:\/\/trimakasi.eu\/wp-content\/uploads\/\u010dakra6-13x12.jpg 13w\" sizes=\"auto, (max-width: 103px) 100vw, 103px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-132743\" src=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/crown-chakra.jpg\" alt=\"Kronenchakra\" width=\"92\" height=\"102\" srcset=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/crown-chakra.jpg 92w, https:\/\/trimakasi.eu\/wp-content\/uploads\/crown-chakra-11x12.jpg 11w\" sizes=\"auto, (max-width: 92px) 100vw, 92px\" \/><\/a><a href=\"https:\/\/trimakasi.eu\/wp-content\/uploads\/crown-chakra.jpg\"><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Ein eleganter Choker aus nat\u00fcrlichem Mondstein. Kleine, facettierte Rondelleperlen schmiegen sich an den Hals und fangen das Licht mit subtilen blauen Reflexen ein \u2013 ein charakteristisches Merkmal von Mondstein. Dank des minimalistischen Designs ist diese Halskette alltagstauglich und perfekt f\u00fcr alle, die schlichten, zeitlosen Schmuck lieben.<\/p>\n<p>Es l\u00e4sst sich auch sehr einfach stylen: Tragen Sie es allein f\u00fcr einen schlichten, eleganten Look oder kombinieren Sie es mit l\u00e4ngeren Halsketten f\u00fcr einen modernen, trendigen Look.<\/p>\n<p>Die Halskette verf\u00fcgt \u00fcber einen verstellbaren Verschluss, sodass sie bequem an verschiedene Halsgr\u00f6\u00dfen passt und den ganzen Tag \u00fcber angenehm zu tragen ist.<\/p>","protected":false},"featured_media":175350,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_themeisle_gutenberg_block_has_review":false},"product_brand":[],"product_cat":[569,1690,1149,1316,553],"product_tag":[],"class_list":["post-175983","product","type-product","status-publish","has-post-thumbnail","product_cat-minimalist-jewellery-for-women","product_cat-necklaces","product_cat-necklaces-for-women","product_cat-rare-gemstone-bracelets","product_cat-womens-jewellery","first","instock","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"_links":{"self":[{"href":"https:\/\/trimakasi.eu\/de\/wp-json\/wp\/v2\/product\/175983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trimakasi.eu\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/trimakasi.eu\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/trimakasi.eu\/de\/wp-json\/wp\/v2\/comments?post=175983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trimakasi.eu\/de\/wp-json\/wp\/v2\/media\/175350"}],"wp:attachment":[{"href":"https:\/\/trimakasi.eu\/de\/wp-json\/wp\/v2\/media?parent=175983"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/trimakasi.eu\/de\/wp-json\/wp\/v2\/product_brand?post=175983"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/trimakasi.eu\/de\/wp-json\/wp\/v2\/product_cat?post=175983"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/trimakasi.eu\/de\/wp-json\/wp\/v2\/product_tag?post=175983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}